{"id":2511,"date":"2023-09-13T10:48:06","date_gmt":"2023-09-13T10:48:06","guid":{"rendered":"https:\/\/tedae.org\/?page_id=2511"},"modified":"2026-03-10T11:11:52","modified_gmt":"2026-03-10T11:11:52","slug":"asociados","status":"publish","type":"page","link":"https:\/\/tedae.org\/en\/asociados\/","title":{"rendered":"Asociados"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2511\" class=\"elementor elementor-2511\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has-el-gap el-gap-default elementor-section elementor-top-section elementor-element elementor-element-5afa1af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5afa1af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0c0635\" data-id=\"a0c0635\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8920a28 elementor-widget elementor-widget-shortcode\" data-id=\"8920a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpgmza-filter-widgets\" data-map-id=\"2\"><input \r\n\t\t\tdata-wpgmza-filter-widget-class=\"WPGMZA\\CustomFieldFilterWidget\\Text\" data-map-id=\"2\" data-field-id=\"1\" =\"\"\r\n\t\t\tplaceholder='N\u00ba empleados'\r\n\t\t\t\/><button type=\"button\" class=\"wpgmza-reset-custom-fields\">Reset<\/button><\/div><div id=\"wpgmza_map_2\" class=\"wpgmza_map wpgmza-auto-center\" style=\"display:block;width:100%;height:600px;overflow:hidden;position:relative;\" data-map-id=\"2\" data-maps-engine=\"open-layers\" data-build-engine=\"atlas-novus\" data-shortcode-attributes=\"{&quot;id&quot;:&quot;2&quot;,&quot;zoom&quot;:false,&quot;width&quot;:false,&quot;height&quot;:false,&quot;marker&quot;:false,&quot;classname&quot;:false,&quot;mashup&quot;:false,&quot;mashup_ids&quot;:false,&quot;cat&quot;:false,&quot;type&quot;:&quot;default&quot;,&quot;parent_id&quot;:false,&quot;lat&quot;:false,&quot;lng&quot;:false,&quot;mark_center&quot;:false,&quot;enable_category&quot;:false,&quot;directions_from&quot;:false,&quot;directions_to&quot;:false,&quot;directions_waypoints&quot;:false,&quot;directions_auto&quot;:false,&quot;disable_vgm_form&quot;:false,&quot;redirect_to&quot;:false}\" data-settings=\"{&quot;map_title&quot;:&quot;Asociados&quot;,&quot;map_width&quot;:&quot;100&quot;,&quot;map_height&quot;:&quot;600&quot;,&quot;map_start_lat&quot;:&quot;40.487488600000006&quot;,&quot;map_start_lng&quot;:&quot;-3.6620433&quot;,&quot;map_start_location&quot;:&quot;&quot;,&quot;map_start_zoom&quot;:&quot;6&quot;,&quot;default_marker&quot;:&quot;&quot;,&quot;type&quot;:&quot;4&quot;,&quot;alignment&quot;:&quot;0&quot;,&quot;directions_enabled&quot;:&quot;0&quot;,&quot;styling_enabled&quot;:&quot;0&quot;,&quot;styling_json&quot;:&quot;&quot;,&quot;active&quot;:&quot;0&quot;,&quot;kml&quot;:&quot;&quot;,&quot;bicycle&quot;:&quot;0&quot;,&quot;traffic&quot;:&quot;0&quot;,&quot;dbox&quot;:&quot;1&quot;,&quot;dbox_width&quot;:&quot;100&quot;,&quot;listmarkers&quot;:&quot;0&quot;,&quot;listmarkers_advanced&quot;:&quot;0&quot;,&quot;filterbycat&quot;:&quot;1&quot;,&quot;ugm_enabled&quot;:&quot;0&quot;,&quot;ugm_category_enabled&quot;:&quot;0&quot;,&quot;fusion&quot;:&quot;&quot;,&quot;map_width_type&quot;:&quot;%&quot;,&quot;map_height_type&quot;:&quot;px&quot;,&quot;mass_marker_support&quot;:&quot;0&quot;,&quot;ugm_access&quot;:&quot;0&quot;,&quot;order_markers_by&quot;:&quot;2&quot;,&quot;order_markers_choice&quot;:&quot;1&quot;,&quot;show_user_location&quot;:&quot;0&quot;,&quot;default_to&quot;:&quot;&quot;,&quot;map_type&quot;:1,&quot;sl_stroke_color&quot;:&quot;#ff0000&quot;,&quot;sl_fill_color&quot;:&quot;#ff0000&quot;,&quot;sl_stroke_opacity&quot;:&quot;1&quot;,&quot;sl_fill_opacity&quot;:&quot;0.5&quot;,&quot;transport_layer&quot;:false,&quot;action&quot;:&quot;wpgmza_save_map&quot;,&quot;redirect_to&quot;:&quot;\\\/wp-admin\\\/admin-post.php&quot;,&quot;map_id&quot;:&quot;2&quot;,&quot;wpgmza_savemap&quot;:&quot;Guardar Mapa&quot;,&quot;http_referer&quot;:&quot;\\\/wp-admin\\\/admin.php?page=wp-google-maps-menu&amp;amp;action=edit&amp;amp;map_id=2&quot;,&quot;wpgmza_id&quot;:&quot;2&quot;,&quot;wpgmza_start_location&quot;:&quot;40.487488600000006,-3.6620433&quot;,&quot;wpgmza_start_zoom&quot;:&quot;6&quot;,&quot;wpgmza_map_align&quot;:&quot;2&quot;,&quot;store_locator_enabled&quot;:false,&quot;store_locator_distance&quot;:false,&quot;store_locator_search_area&quot;:&quot;radial&quot;,&quot;wpgmza_store_locator_default_radius&quot;:&quot;10&quot;,&quot;store_locator_auto_area_max_zoom&quot;:&quot;&quot;,&quot;wpgmza_store_locator_radius_style&quot;:&quot;legacy&quot;,&quot;store_locator_component_anchor&quot;:&quot;0&quot;,&quot;wpgmza_store_locator_bounce&quot;:false,&quot;upload_default_sl_marker&quot;:&quot;&quot;,&quot;upload_default_sl_marker_retina&quot;:false,&quot;wpgmza_sl_animation&quot;:&quot;0&quot;,&quot;store_locator_query_string&quot;:&quot;&quot;,&quot;store_locator_location_placeholder&quot;:&quot;&quot;,&quot;store_locator_default_address&quot;:&quot;&quot;,&quot;store_locator_name_search&quot;:true,&quot;store_locator_name_string&quot;:&quot;&quot;,&quot;store_locator_not_found_message&quot;:&quot;&quot;,&quot;wpgmza_store_locator_restrict&quot;:&quot;es&quot;,&quot;store_locator_show_distance&quot;:false,&quot;store_locator_category&quot;:false,&quot;wpgmza_store_locator_use_their_location&quot;:false,&quot;wpgmza_store_locator_hide_before_search&quot;:false,&quot;store_locator_nearby_searches&quot;:false,&quot;directions_box_component_anchor&quot;:&quot;10&quot;,&quot;wpgmza_dbox_width_type&quot;:&quot;%&quot;,&quot;default_from&quot;:&quot;&quot;,&quot;directions_behaviour&quot;:&quot;default&quot;,&quot;force_google_directions_app&quot;:false,&quot;directions_route_origin_icon&quot;:&quot;https:\\\/\\\/tedae.org\\\/wp-content\\\/plugins\\\/wp-google-maps\\\/images\\\/spotlight-poi3.png&quot;,&quot;directions_origin_retina&quot;:false,&quot;directions_route_destination_icon&quot;:&quot;https:\\\/\\\/tedae.org\\\/wp-content\\\/plugins\\\/wp-google-maps\\\/images\\\/spotlight-poi3.png&quot;,&quot;directions_destination_retina&quot;:false,&quot;directions_route_stroke_color&quot;:&quot;#4d8df5&quot;,&quot;directions_route_stroke_weight&quot;:&quot;4&quot;,&quot;directions_route_stroke_opacity&quot;:&quot;0.8&quot;,&quot;directions_fit_bounds_to_route&quot;:false,&quot;wpgmza_theme_data&quot;:&quot;[]&quot;,&quot;custom_tile_enabled&quot;:false,&quot;custom_tile_image&quot;:&quot;&quot;,&quot;custom_tile_image_width&quot;:&quot;&quot;,&quot;custom_tile_image_height&quot;:&quot;&quot;,&quot;custom_tile_image_attribution&quot;:&quot;&quot;,&quot;iw_primary_color&quot;:&quot;#000000&quot;,&quot;iw_accent_color&quot;:&quot;#000000&quot;,&quot;iw_text_color&quot;:&quot;#000000&quot;,&quot;close_infowindow_on_map_click&quot;:false,&quot;marker_share_links&quot;:false,&quot;wpgmza_listmarkers_by&quot;:&quot;2&quot;,&quot;marker_listing_component_anchor&quot;:&quot;10&quot;,&quot;marker_listing_component_auto_open&quot;:false,&quot;dataTable_pagination_style&quot;:&quot;prev-and-next-buttons-plus-page-numbers&quot;,&quot;category_filter_component_anchor&quot;:&quot;6&quot;,&quot;zoom_level_on_marker_listing_override&quot;:false,&quot;zoom_level_on_marker_listing_click&quot;:&quot;&quot;,&quot;marker_listing_disable_zoom&quot;:false,&quot;datatable_no_result_message&quot;:&quot;&quot;,&quot;remove_search_box_datables&quot;:false,&quot;datatable_search_string&quot;:&quot;&quot;,&quot;datatable_result_start&quot;:&quot;&quot;,&quot;datatable_result_of&quot;:&quot;&quot;,&quot;datatable_result_to&quot;:&quot;&quot;,&quot;datatable_result_total&quot;:&quot;&quot;,&quot;datatable_result_show&quot;:&quot;&quot;,&quot;datatable_result_entries&quot;:&quot;&quot;,&quot;category_legends_enabled&quot;:false,&quot;category_legends_component_anchor&quot;:&quot;9&quot;,&quot;jump_to_nearest_marker_on_initialization&quot;:false,&quot;click_open_link&quot;:false,&quot;wpgmza_zoom_on_marker_click&quot;:false,&quot;wpgmza_zoom_on_marker_click_slider&quot;:&quot;2&quot;,&quot;polygon_labels&quot;:false,&quot;disable_polygon_info_windows&quot;:false,&quot;fit_maps_bounds_to_markers&quot;:false,&quot;fit_maps_bounds_to_markers_after_filtering&quot;:false,&quot;upload_default_ul_marker&quot;:&quot;&quot;,&quot;upload_default_ul_marker_retina&quot;:false,&quot;automatically_pan_to_users_location&quot;:false,&quot;override_users_location_zoom_level&quot;:false,&quot;override_users_location_zoom_levels&quot;:&quot;&quot;,&quot;show_distance_from_location&quot;:false,&quot;map_starts_in_streetview&quot;:false,&quot;map_starts_in_streetview_location&quot;:&quot;&quot;,&quot;map_starts_in_streetview_heading&quot;:&quot;&quot;,&quot;map_starts_in_streetview_pitch&quot;:&quot;&quot;,&quot;map_max_zoom&quot;:&quot;21&quot;,&quot;map_min_zoom&quot;:&quot;0&quot;,&quot;hide_point_of_interest&quot;:false,&quot;retina&quot;:false,&quot;disable_lightbox_images&quot;:false,&quot;use_Raw_Jpeg_Coordinates&quot;:false,&quot;enable_advanced_custom_fields_integration&quot;:false,&quot;enable_toolset_woocommerce_integration&quot;:false,&quot;enable_woo_product_integration&quot;:false,&quot;only_load_markers_within_viewport&quot;:true,&quot;wpgmza_theme&quot;:&quot;0&quot;,&quot;wpgmza_iw_type&quot;:&quot;0&quot;,&quot;enable_advanced_custom_fields_integration_type&quot;:&quot;numero-empleado&quot;,&quot;enable_filter_custom_field_1&quot;:true,&quot;shortcodeAttributes&quot;:{&quot;id&quot;:&quot;2&quot;},&quot;wpgmza_ol_tile_filter&quot;:&quot;none&quot;,&quot;enable_marker_labels&quot;:false,&quot;zoom_level_mobile_override_enabled&quot;:false,&quot;zoom_level_mobile_override&quot;:&quot;&quot;,&quot;id&quot;:2}\" >\n<div class='wpgmza-inner-stack top_right'><div class='wpgmza-marker-listing-category-filter wpgmza-dropdown' data-map-id='2' id='wpgmza_filter_2'><label>Filter by<\/label><select mid=\"2\" id=\"wpgmza_filter_select\" name=\"wpgmza_filter_select\"><option value=\"0\">All<\/option><option value=\"2\">&nbsp;Andaluc\u00eda<\/option><option value=\"10\">&nbsp;Arag\u00f3n<\/option><option value=\"5\">&nbsp;Asturias<\/option><option value=\"6\">&nbsp;Cantabria<\/option><option value=\"14\">&nbsp;Castilla La Mancha<\/option><option value=\"11\">&nbsp;Castilla y Le\u00f3n<\/option><option value=\"9\">&nbsp;Catalu\u00f1a<\/option><option value=\"13\">&nbsp;Comunidad de Madrid<\/option><option value=\"15\">&nbsp;Comunidad Valenciana<\/option><option value=\"12\">&nbsp;Extremadura<\/option><option value=\"4\">&nbsp;Galicia<\/option><option value=\"8\">&nbsp;La Rioja<\/option><option value=\"16\">&nbsp;Murcia<\/option><option value=\"7\">&nbsp;Navarra<\/option><option value=\"3\">&nbsp;Pa\u00eds Vasco<\/option><\/select><\/div><\/div><\/div><div class=\"wpgmza-standalone-component wpgmza-auto-center\" style=\"width:100%; max-width:100%;\" ><div data-wpgmza-table data-wpgmza-php-class=\"WPGMZA\\MarkerListing\\AdvancedTable\" data-wpgmza-rest-api-route=\"\/datatables\/\" data-wpgmza-datatable=\"true\" data-wpgmza-pro-datatable=\"true\" data-wpgmza-feature-type=\"marker\" data-order-json='[[0,\"asc\"]]' id=\"wpgmza_marker_holder_2\" class=\"wpgmza_marker_holder\" style=\"width:100%;\" data-wpgmza-ajax-parameters='{\"map_id\":2}'>\r\n\t\t\t<table class=\"responsive wpgmza_table\" id=\"wpgmza_table_2\" cellspacing=\"0\" cellpadding=\"0\" style=\"width:100%;\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t<th data-wpgmza-column-name=\"title\" id=\"wpgmza_map_list_title\" class=\"all wpgmza_table_title\">Title<\/th><th data-wpgmza-column-name=\"category\" id=\"wpgmza_map_list_category\" class=\"wpgmza_table_category\">Category<\/th><th data-wpgmza-column-name=\"address\" id=\"wpgmza_map_list_address\" class=\"wpgmza_table_address\">Address<\/th><th data-wpgmza-column-name=\"link\" id=\"wpgmza_map_list_link\" class=\"wpgmza_table_link\">Link<\/th><th data-wpgmza-column-name=\"custom_field_1\" id=\"wpgmza_map_list_custom_field_1\" class=\"wpgmza_table_custom_field_1\">N\u00ba empleados<\/th><\/thead>\r\n\t\t\t\t\r\n\t\t\t<\/table>\r\n\t\t<\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e3e67a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e3e67a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e393219\" data-id=\"e393219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1faa64a elementor-grid-5 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-portfolio\" data-id=\"1faa64a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;5&quot;,&quot;item_ratio&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.55,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;item_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-portfolio elementor-grid elementor-posts-container\" role=\"list\">\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17191 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/abaqo-ingenieria-iberia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo.jpg\" class=\"attachment-full size-full wp-image-17192\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/logo-abaqo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAbaqo Ingenier\u00eda Iberia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-16727 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/adatica-engineering\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica.jpg\" class=\"attachment-full size-full wp-image-16728\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/adatica-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAd\u00e1tica Engineering\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11258 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aernnova\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova.jpg\" class=\"attachment-full size-full wp-image-11259\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/aernnova-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAernnova Aerospace\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11240 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aertec\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec.jpg\" class=\"attachment-full size-full wp-image-11283\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aertec-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAertec\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19782 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aerys\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1.jpg\" class=\"attachment-full size-full wp-image-19783\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/aerys-645-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAerys\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11260 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aicox-soluciones\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX.jpg\" class=\"attachment-full size-full wp-image-17382\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/nuevo-logo-AICOX-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAicox Soluciones\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11273 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/airbus\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus.jpg\" class=\"attachment-full size-full wp-image-11276\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbus-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAirbus\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11284 asociado type-asociado status-publish has-post-thumbnail category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/airbus-crisa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa.jpg\" class=\"attachment-full size-full wp-image-11902\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_airbusCrisa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAirbus Crisa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20006 asociado type-asociado status-publish\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/airtificial-aerospace-defense-engineering\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAirtificial Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18141 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/akkodis-technologies-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis.jpg\" class=\"attachment-full size-full wp-image-18142\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/akkodis-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAkkodis Technologies Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12314 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/alfariver\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver.jpg\" class=\"attachment-full size-full wp-image-17188\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo-alfariver-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAlfariver\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11291 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/alpha-unmanned-systems\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha.jpg\" class=\"attachment-full size-full wp-image-17078\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/alpha-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAlpha Unmanned Systems\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11466 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/alten-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten.jpg\" class=\"attachment-full size-full wp-image-12506\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_alten-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAlten Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11331 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/alter\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Logos_alter.jpg\" class=\"attachment-full size-full wp-image-11332\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Logos_alter.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Logos_alter-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Logos_alter-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Logos_alter-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAlter Technology\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19632 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/altia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625.jpg\" class=\"attachment-full size-full wp-image-19646\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/02\/altia_identifier_main-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAltia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11333 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/anzen-aerospace-engineering\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1.jpg\" class=\"attachment-full size-full wp-image-18784\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/imagen1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAnzen Aerospace Engineering\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11335 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/applus-laboratories\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus.jpg\" class=\"attachment-full size-full wp-image-11336\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_applus-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tApplus+ Laboratories\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11425 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aritex\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex.jpg\" class=\"attachment-full size-full wp-image-11427\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_aritex-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAritex\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20467 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/armmo-defense-technologies\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo.jpg\" class=\"attachment-full size-full wp-image-20468\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/armmo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tArmmo Defense Technologies\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11452 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/arpa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa.jpg\" class=\"attachment-full size-full wp-image-11456\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arpa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tArpa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11457 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/arquimea-group\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea.jpg\" class=\"attachment-full size-full wp-image-11458\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_arquimea-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tArqu\u00edmea Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11462 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/autek-ingenieria\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo.jpg\" class=\"attachment-full size-full wp-image-17434\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/autek-nuevo-logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAutek Ingenier\u00eda\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-16714 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/axter-aerospace\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter.jpg\" class=\"attachment-full size-full wp-image-16715\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/01\/logo-axter-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAxter Aerospace\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20233 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/aytana-aeroespacio-y-defensa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645.jpg\" class=\"attachment-full size-full wp-image-20252\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/05\/aytana-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tAytana Aeroespacio y Defensa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11469 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/beonesec-cybersecurity-solutions\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec.jpg\" class=\"attachment-full size-full wp-image-11470\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_beonesec-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBeOneSec Cybersecurity Solutions\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11471 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/bertrandt-technology-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt.jpg\" class=\"attachment-full size-full wp-image-11472\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_bertrandt-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBertrandt Technology Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19399 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/between-technology\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625.jpg\" class=\"attachment-full size-full wp-image-19648\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/Between_Group_logo-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tBetween Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11473 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/capgemini\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645.jpg\" class=\"attachment-full size-full wp-image-20229\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/Capgemini_Primary-logo_Capgemini-Blue_RGB-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCapgemini\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11481 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/centum\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum.jpg\" class=\"attachment-full size-full wp-image-11482\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_centum-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCentum\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11483 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/cesa-heroux-devtek-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo.jpg\" class=\"attachment-full size-full wp-image-17080\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/cesa-logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCESA \/ H\u00e9roux-Devtek Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17756 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/cipherbit\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit.jpg\" class=\"attachment-full size-full wp-image-17757\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_cipherbit-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCipherbit\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11492 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/clue-technologies\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue.jpg\" class=\"attachment-full size-full wp-image-11493\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_clue-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tClue Technologies\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18797 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/comercial-torrents\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1.jpg\" class=\"attachment-full size-full wp-image-18849\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/Torrents-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tComercial Torrents\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11498 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/ct-engineering-group\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT.jpg\" class=\"attachment-full size-full wp-image-11499\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_CT-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tCT Engineering Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11504 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/dars-telecom\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars.jpg\" class=\"attachment-full size-full wp-image-11505\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_dars-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDars Telecom\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11801 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/das-photonics\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das.jpg\" class=\"attachment-full size-full wp-image-11807\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_das-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDas Photonics\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11820 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/delta-vigo-delta-group-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo.jpg\" class=\"attachment-full size-full wp-image-11829\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_delta-vigo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDelta Vigo &#8211; Delta Group Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11830 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/destinus-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus.jpg\" class=\"attachment-full size-full wp-image-11834\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_destinus-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDestinus Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17384 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/dhv-tecnologia-espacial-avanzada-malaguena\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo.jpg\" class=\"attachment-full size-full wp-image-17385\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/dhv-logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDhv Tecnolog\u00eda Espacial Avanzada Malague\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11835 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/duma-engineering-group\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma.jpg\" class=\"attachment-full size-full wp-image-11836\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_duma-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tDuma Engineering Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19781 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/ega-master\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625.jpg\" class=\"attachment-full size-full wp-image-19784\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/ega-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEga Master\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11854 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/electronica-informatica-instrumentacion-y-telecomunicacion\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit.jpg\" class=\"attachment-full size-full wp-image-11883\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_eiit-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEIIT\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11842 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/einsa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa.jpg\" class=\"attachment-full size-full wp-image-11843\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_einsa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEinsa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11892 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/escribano-mechanical-and-engineering\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1.png\" class=\"attachment-full size-full wp-image-16620\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1.png 645w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1-300x169.png 300w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1-18x10.png 18w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1-150x84.png 150w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/logo_eme-1-450x253.png 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEM&#038;E GROUP\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11887 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/epicom\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo.jpg\" class=\"attachment-full size-full wp-image-17081\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/epicon-logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEpicom\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18741 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/etra-air\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11.jpg\" class=\"attachment-full size-full wp-image-18743\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/etrair11-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEtra Air\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11897 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/europavia-espana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia.jpg\" class=\"attachment-full size-full wp-image-11898\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_europavia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tEuropavia Espa\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19173 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/exceltic\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625.jpg\" class=\"attachment-full size-full wp-image-19448\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/exceltic-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tExceltic\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11903 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/fabrica-de-municiones-granada\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG.jpg\" class=\"attachment-full size-full wp-image-11913\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_FMG-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tF\u00e1brica de Municiones Granada\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18694 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/factor-ingenieria-y-decoletaje\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece.jpg\" class=\"attachment-full size-full wp-image-18695\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/logo_factor-defece-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFactor Ingenier\u00eda y Decoletaje\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11955 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/fundacion-tecnalia-research-innovation\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia.jpg\" class=\"attachment-full size-full wp-image-11957\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/logo_tecnalia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tFundaci\u00f3n Tecnalia Research &#038; Innovation\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11983 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/gdels-santa-barbara-sistemas\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645.jpg\" class=\"attachment-full size-full wp-image-20177\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/gdels-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGDELS &#8211; Santa B\u00e1rbara Sistemas\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-15644 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/ghenova-ingenieria\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/07\/ghenova.jpg\" class=\"attachment-full size-full wp-image-15645\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/07\/ghenova.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/07\/ghenova-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/07\/ghenova-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/07\/ghenova-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGhenova Ingenier\u00eda\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11988 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/gmv\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV.jpg\" class=\"attachment-full size-full wp-image-11989\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_GMV-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGMV\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11999 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/grabysur\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur.jpg\" class=\"attachment-full size-full wp-image-12001\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grabysur-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGrabysur\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12016 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/grupo-alava\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava.jpg\" class=\"attachment-full size-full wp-image-12017\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupo-Alava-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGrupo \u00c1lava\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12030 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/grupo-amper\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1.jpg\" class=\"attachment-full size-full wp-image-12040\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_grupoamper-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGrupo Amper\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12337 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/grupo-oesia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia.jpg\" class=\"attachment-full size-full wp-image-12338\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2023\/07\/grupo-oesia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGrupo Oes\u00eda\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12041 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/gtd\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd.jpg\" class=\"attachment-full size-full wp-image-12042\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_gtd-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tGTD\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12046 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/hisdesat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat.jpg\" class=\"attachment-full size-full wp-image-12047\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_hisdesat-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHisdesat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12051 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/hispasat\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT.png\" class=\"attachment-full size-full wp-image-19875\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT.png 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT-300x169.png 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT-18x10.png 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT-150x84.png 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HISPASAT-450x253.png 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHispasat\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12056 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/hv-sistemas\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV.jpg\" class=\"attachment-full size-full wp-image-12057\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_HV-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tHV Sistemas\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12060 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/i-4s\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s.jpg\" class=\"attachment-full size-full wp-image-12061\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_i4s-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\ti-4s\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19823 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/iceye-espana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645.jpg\" class=\"attachment-full size-full wp-image-19824\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/iceye-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIceye Espa\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12065 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/indra-group\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1.jpg\" class=\"attachment-full size-full wp-image-19708\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/AF_INDRAGROUP_LOG_POS-625-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIndra Group\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11808 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/indra-space\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra.jpg\" class=\"attachment-full size-full wp-image-12066\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_indra-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIndra Space\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12070 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/industrial-olmar\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar.jpg\" class=\"attachment-full size-full wp-image-12071\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_olmar-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIndustrial Olmar\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18186 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/industrias-puigjaner\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn.jpg\" class=\"attachment-full size-full wp-image-18189\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/07\/denn-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIndustrias Puigjaner &#8211; Denn\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12075 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/inespasa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa.jpg\" class=\"attachment-full size-full wp-image-12076\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inespasa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInespasa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12084 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/inetum-espana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/inetum.jpg\" class=\"attachment-full size-full wp-image-15929\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/inetum.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/inetum-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/inetum-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/inetum-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInetum Espa\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20476 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/innovaciones-tecnologicas-del-sur\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur.jpg\" class=\"attachment-full size-full wp-image-20480\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/07\/InnovaSur-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInnovaciones Tecnol\u00f3gicas del Sur\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12094 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/instalaza\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo.jpg\" class=\"attachment-full size-full wp-image-14401\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_instalaza_nuevo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInstalaza\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12102 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/inster-grupo-oesia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster.jpg\" class=\"attachment-full size-full wp-image-12104\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inster-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInster &#8211; Grupo Oes\u00eda\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12116 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/insyte\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte.jpg\" class=\"attachment-full size-full wp-image-12117\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_insyte-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInsyte\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12121 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/integrasys\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1.jpg\" class=\"attachment-full size-full wp-image-16464\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/integrasys-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIntegrasys\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12124 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/inventia-kinetics\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia.jpg\" class=\"attachment-full size-full wp-image-12128\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_inventia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tInventia Kinetics\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12141 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/iraundi\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi.jpg\" class=\"attachment-full size-full wp-image-12154\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_iraundi-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tIraundi\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12163 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/itp-aero\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp.jpg\" class=\"attachment-full size-full wp-image-16698\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_itp-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tITP Aero\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12172 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/ka-safe-engineering-consulting\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe.jpg\" class=\"attachment-full size-full wp-image-12173\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_Ka-safe-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tKA SAFE Engineering Consulting\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17346 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/latesys-iberia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo.jpg\" class=\"attachment-full size-full wp-image-17350\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/04\/latesys_logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLatesys Iberia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19327 asociado type-asociado status-publish has-post-thumbnail category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/lidax\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625.jpg\" class=\"attachment-full size-full wp-image-19785\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/lidax-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tLidax\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12175 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/mades\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades.jpg\" class=\"attachment-full size-full wp-image-12176\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mades-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMADES\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17718 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/marine-instruments\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments.jpg\" class=\"attachment-full size-full wp-image-17722\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/logo_marine-instruments-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMarine Instruments\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12180 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/masa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa.jpg\" class=\"attachment-full size-full wp-image-12181\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_masa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMasa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12187 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/mbda\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo.jpg\" class=\"attachment-full size-full wp-image-17082\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/mbda-logo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMBDA\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12194 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/mecanica-de-precision-tejedor\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica.jpg\" class=\"attachment-full size-full wp-image-12195\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_mecanica-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMec\u00e1nica de Precisi\u00f3n Tejedor\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12197 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/meltio-directedmetal-3d\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio.jpg\" class=\"attachment-full size-full wp-image-12198\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_meltio-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMeltio (DirectedMetal 3D)\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-16943 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/mercury-mission-systems-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury.jpg\" class=\"attachment-full size-full wp-image-16944\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/02\/mercury-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMercury Mission Systems Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17427 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/metalmecanicas-herjimar\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar.jpg\" class=\"attachment-full size-full wp-image-17433\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/05\/herjimar-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMetalmec\u00e1nicas Herjimar\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19024 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/metodos-y-tecnologia-de-sistemas-y-procesos\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25.jpg\" class=\"attachment-full size-full wp-image-19068\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/11\/Imagen-MTP-2.12.25-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tM\u00e9todos y Tecnolog\u00eda de Sistemas y Procesos\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12202 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/mtorres\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres.jpg\" class=\"attachment-full size-full wp-image-12203\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_mtorres-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMTorres\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20402 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/multiverse-computing\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse.jpg\" class=\"attachment-full size-full wp-image-20464\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/multiverse-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMultiverse Computing\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12208 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/myc\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC.jpg\" class=\"attachment-full size-full wp-image-12209\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_MYC-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tMYC\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12214 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/nammo-palencia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo.jpg\" class=\"attachment-full size-full wp-image-12215\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_nammo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNammo Palencia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12219 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/navantia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia.jpg\" class=\"attachment-full size-full wp-image-12220\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_navantia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNavantia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19854 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/nerva-technologies\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA.png\" class=\"attachment-full size-full wp-image-19864\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA.png 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA-300x169.png 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA-18x10.png 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA-150x84.png 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/03\/logo_NERVA-450x253.png 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNerva Technologies\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18799 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/novaexterna-3d\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1.jpg\" class=\"attachment-full size-full wp-image-18903\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/10\/novaindef-625-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNovaindef\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17236 asociado type-asociado status-publish has-post-thumbnail category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/nunsys\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys.jpg\" class=\"attachment-full size-full wp-image-17259\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/03\/nunsys-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tNunsys\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12224 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/orbital-sistemas-aeroespaciales\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital.jpg\" class=\"attachment-full size-full wp-image-12225\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_orbital-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tOrbital Sistemas Aeroespaciales\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20356 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/pangea-aerospace\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645.jpg\" class=\"attachment-full size-full wp-image-20364\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/pangea-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPangea Propulsi\u00f3n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12228 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/pap-tecnos-innovacion\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos.jpg\" class=\"attachment-full size-full wp-image-12229\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pap_tecnos-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPap Tecnos Innovaci\u00f3n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12233 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/piedrafita-systems\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita.jpg\" class=\"attachment-full size-full wp-image-12234\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_piedrafita-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPiedrafita Systems\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12239 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/pld-space\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace.jpg\" class=\"attachment-full size-full wp-image-12240\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_pldspace-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPLD Space\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-14405 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/precision-manufacturing-aerospace\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg.jpg\" class=\"attachment-full size-full wp-image-14406\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/05\/Logos_pma_jpg-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPrecision Manufacturing Aerospace\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20334 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/promega\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645.jpg\" class=\"attachment-full size-full wp-image-20359\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/promega-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tPromega\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12244 asociado type-asociado status-publish has-post-thumbnail category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/quasar-science-resources\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar.jpg\" class=\"attachment-full size-full wp-image-12248\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quasar-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tQuasar Science Resources\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12250 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/quest-global-engineering-espana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest.jpg\" class=\"attachment-full size-full wp-image-12251\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_quest-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tQuest Global Engineering Espa\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12252 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/rheinmetall-expal-munitions\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal.jpg\" class=\"attachment-full size-full wp-image-12253\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_expal-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRheinmetall Expal Munitions\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20327 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/rm-trade\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635.jpg\" class=\"attachment-full size-full wp-image-20329\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/rmt-635-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRM TRADE\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12255 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/rohde-schwarz-espana\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde.jpg\" class=\"attachment-full size-full wp-image-12256\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/Logo_rohde-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tRohde &#038; Schwarz Espa\u00f1a\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18434 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/s4a-solutions-for-aviation\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A.jpg\" class=\"attachment-full size-full wp-image-18435\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-s4A-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tS4A Solutions for Aviation\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12279 asociado type-asociado status-publish has-post-thumbnail category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/saes-sociedad-anonima-de-electronica-submarina-s-m-e\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes.jpg\" class=\"attachment-full size-full wp-image-12280\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_saes-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSAES \u2013 Sociedad An\u00f3nima de Electr\u00f3nica Submarina, S.M.E.\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12285 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sainsel-sistemas-navales\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel.jpg\" class=\"attachment-full size-full wp-image-12286\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sainsel-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSainsel Sistemas Navales\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12290 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sapa-placencia\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa.jpg\" class=\"attachment-full size-full wp-image-12291\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sapa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSapa Placencia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20405 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sateliot-iot-services\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot.jpg\" class=\"attachment-full size-full wp-image-20466\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/sateliot-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSateliot Iot Services\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12296 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/satlantis-microsats\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis.jpg\" class=\"attachment-full size-full wp-image-12297\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_satlantis-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSatlantis Microsats\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20335 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/schmidt-clements-spain\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645.jpg\" class=\"attachment-full size-full wp-image-20363\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/scs-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSchmidt-Clements Spain\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12319 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sener\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener.jpg\" class=\"attachment-full size-full wp-image-12320\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sener-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSener\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-17754 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sitep\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap.jpg\" class=\"attachment-full size-full wp-image-17755\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/06\/logo_sitemap-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSITEP\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20272 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/soc-e\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1.jpg\" class=\"attachment-full size-full wp-image-20300\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/soce-645-550-1-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSOC-E\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20328 asociado type-asociado status-publish has-post-thumbnail category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/solar-mems-technologies\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645.jpg\" class=\"attachment-full size-full wp-image-20330\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/solarmems-645-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSolar MEMS Technologies\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-11147 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sonaca-espana-aeronautica\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca.jpg\" class=\"attachment-full size-full wp-image-20469\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/01\/sonaca-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSonaca Espa\u00f1a Aeron\u00e1utica\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12308 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/sopra-steria-cimpa\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra.jpg\" class=\"attachment-full size-full wp-image-12309\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_sopra-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSopra Steria \/ Cimpa\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19065 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/startical\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12.jpg\" class=\"attachment-full size-full wp-image-19066\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/12\/Logo-2.12-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tStartical\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-20406 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/subcontrataciones-industriales\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa.jpg\" class=\"attachment-full size-full wp-image-20465\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/06\/suinsa-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tSubcontrataciones Industriales\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12328 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/technology-security-developments\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD.jpg\" class=\"attachment-full size-full wp-image-12329\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_TSD-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTechnology &#038; Security Developments\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12334 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/tecnatom\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom.jpg\" class=\"attachment-full size-full wp-image-12335\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_tecnatom-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTecnatom\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12343 asociado type-asociado status-publish has-post-thumbnail category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/telespazio-iberica\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio.jpg\" class=\"attachment-full size-full wp-image-12344\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_telespazio-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTelespazio Ib\u00e9rica\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12347 asociado type-asociado status-publish has-post-thumbnail category-aeronautica\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/temai-ingenieros\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai.jpg\" class=\"attachment-full size-full wp-image-12348\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_temai-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTemai Ingenieros\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12352 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa category-seguridad\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/thales\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales.jpg\" class=\"attachment-full size-full wp-image-12354\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thales-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tThales\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12358 asociado type-asociado status-publish has-post-thumbnail category-defensa category-espacio\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/thales-alenia-space\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia.jpg\" class=\"attachment-full size-full wp-image-12359\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_thalesalenia-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tThales Alenia Space\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-19397 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/thune-eureka\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625.jpg\" class=\"attachment-full size-full wp-image-19398\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2026\/01\/thuneeureka-625-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tThune Eureka\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12364 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/trigo-group\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo.jpg\" class=\"attachment-full size-full wp-image-12365\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_trigo-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tTrigo ADR Iberia\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-16466 asociado type-asociado status-publish has-post-thumbnail category-aeronautica category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/uav-navigation\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation.jpg\" class=\"attachment-full size-full wp-image-16467\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/12\/uav-navigation-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tUAV NAVIGATION\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-12369 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/uro\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO.jpg\" class=\"attachment-full size-full wp-image-12370\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2024\/02\/logo_URO-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tUro Veh\u00edculos Especiales\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-portfolio-item elementor-post  post-18436 asociado type-asociado status-publish has-post-thumbnail category-defensa\" role=\"listitem\">\n\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tedae.org\/en\/asociado\/virtualware-2007\/\">\n\t\t\t\t<div class=\"elementor-portfolio-item__img elementor-post__thumbnail\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"363\" src=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware.jpg\" class=\"attachment-full size-full wp-image-18437\" alt=\"\" srcset=\"https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware.jpg 645w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware-300x169.jpg 300w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware-18x10.jpg 18w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware-150x84.jpg 150w, https:\/\/tedae.org\/wp-content\/uploads\/2025\/09\/logo-virtualware-450x253.jpg 450w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-portfolio-item__overlay\">\n\t\t\t\t<h3 class=\"elementor-portfolio-item__title\">\n\t\tVirtualware\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"footnotes":""},"class_list":["post-2511","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asociados - TEDAE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tedae.org\/en\/asociados\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asociados - TEDAE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tedae.org\/en\/asociados\/\" \/>\n<meta property=\"og:site_name\" content=\"TEDAE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T11:11:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@espaciotedae\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tedae.org\\\/asociados\\\/\",\"url\":\"https:\\\/\\\/tedae.org\\\/asociados\\\/\",\"name\":\"Asociados - TEDAE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#website\"},\"datePublished\":\"2023-09-13T10:48:06+00:00\",\"dateModified\":\"2026-03-10T11:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tedae.org\\\/asociados\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tedae.org\\\/asociados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tedae.org\\\/asociados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tedae.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asociados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tedae.org\\\/en\\\/\",\"name\":\"TEDAE\",\"description\":\"Defensa, Seguridad, Aeron\u00e1utica y Espacio\",\"publisher\":{\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tedae.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#organization\",\"name\":\"TEDAE, Defensa, Seguridad, Aeron\u00e1utica y Espacio\",\"url\":\"https:\\\/\\\/tedae.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tedae.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-svg-color.svg\",\"contentUrl\":\"https:\\\/\\\/tedae.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo-svg-color.svg\",\"width\":300,\"height\":85,\"caption\":\"TEDAE, Defensa, Seguridad, Aeron\u00e1utica y Espacio\"},\"image\":{\"@id\":\"https:\\\/\\\/tedae.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/espaciotedae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tedae\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvtCvdowrYJGJGdnUKRKeSg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asociados - TEDAE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tedae.org\/en\/asociados\/","og_locale":"en_GB","og_type":"article","og_title":"Asociados - TEDAE","og_url":"https:\/\/tedae.org\/en\/asociados\/","og_site_name":"TEDAE","article_modified_time":"2026-03-10T11:11:52+00:00","twitter_card":"summary_large_image","twitter_site":"@espaciotedae","twitter_misc":{"Estimated reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tedae.org\/asociados\/","url":"https:\/\/tedae.org\/asociados\/","name":"Asociados - TEDAE","isPartOf":{"@id":"https:\/\/tedae.org\/en\/#website"},"datePublished":"2023-09-13T10:48:06+00:00","dateModified":"2026-03-10T11:11:52+00:00","breadcrumb":{"@id":"https:\/\/tedae.org\/asociados\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tedae.org\/asociados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tedae.org\/asociados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tedae.org\/"},{"@type":"ListItem","position":2,"name":"Asociados"}]},{"@type":"WebSite","@id":"https:\/\/tedae.org\/en\/#website","url":"https:\/\/tedae.org\/en\/","name":"TEDAE","description":"Defensa, Seguridad, Aeron\u00e1utica y Espacio","publisher":{"@id":"https:\/\/tedae.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tedae.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/tedae.org\/en\/#organization","name":"TEDAE, Defensa, Seguridad, Aeron\u00e1utica y Espacio","url":"https:\/\/tedae.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/tedae.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tedae.org\/wp-content\/uploads\/2024\/04\/logo-svg-color.svg","contentUrl":"https:\/\/tedae.org\/wp-content\/uploads\/2024\/04\/logo-svg-color.svg","width":300,"height":85,"caption":"TEDAE, Defensa, Seguridad, Aeron\u00e1utica y Espacio"},"image":{"@id":"https:\/\/tedae.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/espaciotedae","https:\/\/www.linkedin.com\/company\/tedae","https:\/\/www.youtube.com\/channel\/UCvtCvdowrYJGJGdnUKRKeSg"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/pages\/2511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/comments?post=2511"}],"version-history":[{"count":91,"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/pages\/2511\/revisions"}],"predecessor-version":[{"id":19763,"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/pages\/2511\/revisions\/19763"}],"wp:attachment":[{"href":"https:\/\/tedae.org\/en\/wp-json\/wp\/v2\/media?parent=2511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}